{"id":9435,"date":"2025-07-07T12:26:31","date_gmt":"2025-07-07T10:26:31","guid":{"rendered":"https:\/\/xcaliburmp.com\/?post_type=technology&#038;p=9435"},"modified":"2025-07-11T09:57:41","modified_gmt":"2025-07-11T07:57:41","slug":"magcube","status":"publish","type":"technology","link":"https:\/\/xcaliburmp.com\/pt-pt\/technology\/magcube\/","title":{"rendered":"MagCUBE\u2122"},"content":{"rendered":"<div id=\"Breadcrumb-block_eb7e0fa9c5d434dd02580383db3bb0a3\" class=\"Breadcrumb\" >\n    <section class=\"breadcrumb\" id=\"breadcrumbs\">\n        <div class=\"container\">\n            <nav aria-label=\"Breadcrumb\" class=\"breadcrumb\">\n                <ul class=\"breadcrumb_list\">\n                                                                        <li class=\"breadcrumb_item\"><a target=\"\" class=\" breadcrumb_link\" href=\"\/\">Home<\/a><\/li>\n                                                    <li class=\"breadcrumb_item\"><a target=\"\" class=\" breadcrumb_link\" href=\"https:\/\/xcaliburmp.com\/technologies\/\">Technologies<\/a><\/li>\n                                                                <li class=\"breadcrumb_item\"><span class=\" breadcrumb_current\">MagCUBE\u2122<\/span><\/li>\n                <\/ul>\n            <\/nav>\n        <\/div>\n    <\/section>\n<\/div>\n\n\n\r\n<div id=\"OpeningImage-block_53e27a2bdb2c2ab5b78c09e6923f1330\" class=\"OpeningImage\" style=\"background-image: url('https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/05\/ChatGPT-Image-27-may-2025-14_47_13.png')\" >\r\n    <section class=\"opening-image\" id=\"s-openingImage\">\r\n        <div class=\"container\">\r\n            <div class=\"row\">\r\n                <div class=\"col-12\">\r\n                    <h1 class=\"title\">MagCUBE\u2122<\/h1>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/section>\r\n<\/div>\r\n\r\n<script>\r\n    jQuery( document ).ready(function($) {\r\n        setTimeout(function() {\r\n            $('.OpeningImage .title').slideDown(1200)\r\n        }, 300 );\r\n    })\r\n<\/script>\r\n\r\n\n\n\r\n<div id=\"FixedText-block_d40e8cae3b08a5e31e25f51bb82df126\" class=\"FixedText\" >\r\n    <div class=\"text\">SOFTWARE<\/div>\r\n<\/div>\n\n\r\n<div id=\"HighlightedTextESG-block_a6c01969183cef92833e2b647fc3e753\" class=\"v3 HighlightedTextESG\" >\r\n    <section class=\"highlightedText\" id=\"higlightedText\">\r\n        <div class=\"container\">\r\n            <div class=\"content\">\r\n                <h3 class=\"kicker\"><\/h3>\r\n                <div class=\"description no-indent\"><p><strong>MagCUBE\u2122 converte anomalias escalares da intensidade magn\u00e9tica total<\/strong> observadas na superf\u00edcie em uma distribui\u00e7\u00e3o vetorial do campo magn\u00e9tico cortical no subsolo<\/p>\n<\/div>\r\n            <\/div>\r\n        <\/div>\r\n            <\/section>\r\n<\/div>\n\n\r\n<div id=\"TextImages-block_d414f6222f9ac79efde33bf94032185a\" class=\"TextImages\" style=\"background-color:\">\r\n\r\n    <section class=\"textimages\">\r\n        \r\n            <!-- NUEVOS FORMATOS -->\r\n                            <div class=\"container\">\r\n                                        <div class=\"wrapper_fullTextImageNew w-full\">\r\n                        <div class=\"text\">\r\n                            <h3 class=\"title\"><\/h3>\r\n                            <div class=\"description\" style=\"color:\"><h2><span style=\"color: #ff3300;\">MagCUBE\u2122: Modelos IFR para Posicionamento Preciso do Po\u00e7o em Perfura\u00e7\u00e3o Horizontal e Direcional<\/span><\/h2>\n<p>MagCUBE\u2122 constr\u00f3i um modelo IFR (referenciamento em campo) para melhorar o posicionamento do po\u00e7o em perfura\u00e7\u00f5es horizontais e direcionais. Constru\u00edmos um modelo IFR com algumas considera\u00e7\u00f5es diferenciais. Primeiro, utilizamos a restri\u00e7\u00e3o geol\u00f3gica (funda\u00e7\u00e3o rochosa). Segundo, utilizamos declina\u00e7\u00f5es vari\u00e1veis e inclina\u00e7\u00f5es vari\u00e1veis na convers\u00e3o de um campo escalar em um campo vetorial. Terceiro, utilizamos dados magn\u00e9ticos de alta resolu\u00e7\u00e3o. Juntamente com nossas capacidades globais de aquisi\u00e7\u00e3o de dados aeromagn\u00e9ticos, operadores e perfuradores agora t\u00eam modelos IFR precisos e facilmente acess\u00edveis. MagCUBE\u2122 tem sido bem-sucedido na melhoria da precis\u00e3o de posicionamento e na redu\u00e7\u00e3o de custos em projetos de perfura\u00e7\u00e3o horizontal e direcional globalmente.<\/p>\n<h3><span style=\"color: #ff3300;\">A Import\u00e2ncia da Precis\u00e3o no Posicionamento em Perfura\u00e7\u00f5es Horizontais e Direcionais<\/span><\/h3>\n<p>A perfura\u00e7\u00e3o horizontal e direcional maximiza a extra\u00e7\u00e3o de petr\u00f3leo e g\u00e1s enquanto minimiza os custos. Po\u00e7os horizontais e direcionais s\u00e3o constantemente perfurados mais longos e com espa\u00e7amentos menores, enquanto os alvos geol\u00f3gicos se tornam ainda menores. A incerteza de posicionamento aumenta com a dist\u00e2ncia perfurada. \u00c9 crucial reduzir a incerteza de posicionamento ou melhorar a precis\u00e3o na medi\u00e7\u00e3o e no posicionamento em perfura\u00e7\u00f5es horizontais e direcionais.<\/p>\n<\/div>\r\n                        <\/div>\r\n                        <div class=\"image\">\r\n                                                            <img decoding=\"async\" width=\"1024\" height=\"1536\" src=\"https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/05\/ChatGPT-Image-27-may-2025-14_20_52-e1752486879354.png\" class=\"\" alt=\"ChatGPT Image 27 may 2025, 14_20_52\" loading=\"lazy\" \/>                                                    <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n                <\/section>\r\n\r\n\r\n<\/div>\n\n\r\n<div id=\"TextImages-block_c07715a62ceef26653f0983887443553\" class=\"TextImages\" style=\"background-color:\">\r\n\r\n    <section class=\"textimages\">\r\n        \r\n            <!-- NUEVOS FORMATOS -->\r\n                            <div class=\"container\">\r\n                                            <div class=\"border\" style=\"background-color:#451b17\"><\/div>\r\n                                        <div class=\"wrapper_fullImageTextNew w-full\">\r\n                        <div class=\"image\">\r\n                                                            <img decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/05\/Post-de-Instagram-Amor-San-Valentin-moderno-en-rosa-y-blanco.png\" class=\"\" alt=\"Post de Instagram Amor San Valenti\u0301n moderno en rosa y blanco\" loading=\"lazy\" srcset=\"https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/05\/Post-de-Instagram-Amor-San-Valentin-moderno-en-rosa-y-blanco.png 1080w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/05\/Post-de-Instagram-Amor-San-Valentin-moderno-en-rosa-y-blanco-300x300.png 300w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/05\/Post-de-Instagram-Amor-San-Valentin-moderno-en-rosa-y-blanco-1024x1024.png 1024w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/05\/Post-de-Instagram-Amor-San-Valentin-moderno-en-rosa-y-blanco-150x150.png 150w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/05\/Post-de-Instagram-Amor-San-Valentin-moderno-en-rosa-y-blanco-768x768.png 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/>                                                    <\/div>\r\n                        <div class=\"text\">\r\n                            <h3 class=\"title\"><\/h3>\r\n                            <div class=\"description\" style=\"color:#451b17\"><h3><span style=\"color: #ff3300;\">A Medida Durante a Perfura\u00e7\u00e3o (MWD)<\/span><\/h3>\n<p>A Medida Durante a Perfura\u00e7\u00e3o (MWD) descreve a pesquisa direcional e as medi\u00e7\u00f5es relacionadas \u00e0 perfura\u00e7\u00e3o. Uma pesquisa econ\u00f4mica em MWD consiste em medir a dist\u00e2ncia e dois \u00e2ngulos: a inclina\u00e7\u00e3o medida por um aceler\u00f4metro triaxial e o azimute por um magnet\u00f4metro triaxial. A pesquisa magn\u00e9tica baseia-se no princ\u00edpio de medir a dire\u00e7\u00e3o do po\u00e7o em rela\u00e7\u00e3o \u00e0 dire\u00e7\u00e3o do campo geomagn\u00e9tico local. Sua precis\u00e3o \u00e9, portanto, limitada pela exatid\u00e3o com que o campo magn\u00e9tico local da Terra \u00e9 conhecido no local e momento da perfura\u00e7\u00e3o.<\/p>\n<h3><span style=\"color: #ff3300;\">A Import\u00e2ncia de um Modelo de Refer\u00eancia Magn\u00e9tico Preciso<\/span><\/h3>\n<p>Os dados magn\u00e9ticos de superf\u00edcie s\u00e3o essenciais porque o azimute magn\u00e9tico do conjunto de fundo de po\u00e7o (BHA) \u00e9 inferido a partir das medi\u00e7\u00f5es dos componentes vetoriais do instrumento de pesquisa MWD. Para converter o azimute magn\u00e9tico em um azimute verdadeiro, \u00e9 necess\u00e1rio o \u00e2ngulo de declina\u00e7\u00e3o local fornecido por um modelo de refer\u00eancia geomagn\u00e9tico que inclui as varia\u00e7\u00f5es do campo magn\u00e9tico cortical local. Quanto mais preciso for o modelo de refer\u00eancia, mais preciso ser\u00e1 o azimute verdadeiro do BHA, ou seja, o posicionamento do po\u00e7o.<\/p>\n<\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n                <\/section>\r\n\r\n\r\n<\/div>\n\n\r\n<div id=\"ContactUs-block_a491d395f22410d920d7d57cfe4406ef\" class=\"ContactUs\" >\r\n\r\n    <section id=\"cta\" class=\"cta \">\r\n        <div class=\"container\">\r\n            <h3 class=\"cta_title\">Contato.<\/h3>\r\n            <a class=\"cta_button button\" href=\"https:\/\/xcaliburmp.com\/pt-pt\/contato\/\" target=\"\" title=\"PREENCHA O FORMUL\u00c1RIO\">PREENCHA O FORMUL\u00c1RIO<\/a>\r\n        <\/div>\r\n    <\/section><!-- .cta -->\r\n\r\n\r\n    <\/div>","protected":false},"featured_media":0,"template":"","class_list":["post-9435","technology","type-technology","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MagCUBE\u2122 - Xcalibur Smart Mapping<\/title>\n<meta name=\"description\" content=\"MagCUBE\u2122 otimiza a perfura\u00e7\u00e3o horizontal e direcional por meio da constru\u00e7\u00e3o de modelos IFR de alta precis\u00e3o, reduzindo os custos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xcaliburmp.com\/pt-pt\/technology\/magcube\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MagCUBE\u2122 - Xcalibur Smart Mapping\" \/>\n<meta property=\"og:description\" content=\"MagCUBE\u2122 otimiza a perfura\u00e7\u00e3o horizontal e direcional por meio da constru\u00e7\u00e3o de modelos IFR de alta precis\u00e3o, reduzindo os custos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xcaliburmp.com\/pt-pt\/technology\/magcube\/\" \/>\n<meta property=\"og:site_name\" content=\"Xcalibur Smart Mapping\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-11T07:57:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xcaliburmp.com\\\/pt-pt\\\/technology\\\/magcube\\\/\",\"url\":\"https:\\\/\\\/xcaliburmp.com\\\/pt-pt\\\/technology\\\/magcube\\\/\",\"name\":\"MagCUBE\u2122 - Xcalibur Smart Mapping\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xcaliburmp.com\\\/pt-pt\\\/#website\"},\"datePublished\":\"2025-07-07T10:26:31+00:00\",\"dateModified\":\"2025-07-11T07:57:41+00:00\",\"description\":\"MagCUBE\u2122 otimiza a perfura\u00e7\u00e3o horizontal e direcional por meio da constru\u00e7\u00e3o de modelos IFR de alta precis\u00e3o, reduzindo os custos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xcaliburmp.com\\\/pt-pt\\\/technology\\\/magcube\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xcaliburmp.com\\\/pt-pt\\\/technology\\\/magcube\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xcaliburmp.com\\\/pt-pt\\\/technology\\\/magcube\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/xcaliburmp.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MagCUBE\u2122\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xcaliburmp.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/xcaliburmp.com\\\/pt-pt\\\/\",\"name\":\"Xcalibur Smart Mapping\",\"description\":\"Xcalibur Smart Mapping es un l\u00edder mundial en geof\u00edsica a\u00e9rea y marina, interpretaci\u00f3n y procesamiento de datos y servicios de valor agregado.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xcaliburmp.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MagCUBE\u2122 - Xcalibur Smart Mapping","description":"MagCUBE\u2122 otimiza a perfura\u00e7\u00e3o horizontal e direcional por meio da constru\u00e7\u00e3o de modelos IFR de alta precis\u00e3o, reduzindo os custos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xcaliburmp.com\/pt-pt\/technology\/magcube\/","og_locale":"pt_PT","og_type":"article","og_title":"MagCUBE\u2122 - Xcalibur Smart Mapping","og_description":"MagCUBE\u2122 otimiza a perfura\u00e7\u00e3o horizontal e direcional por meio da constru\u00e7\u00e3o de modelos IFR de alta precis\u00e3o, reduzindo os custos.","og_url":"https:\/\/xcaliburmp.com\/pt-pt\/technology\/magcube\/","og_site_name":"Xcalibur Smart Mapping","article_modified_time":"2025-07-11T07:57:41+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xcaliburmp.com\/pt-pt\/technology\/magcube\/","url":"https:\/\/xcaliburmp.com\/pt-pt\/technology\/magcube\/","name":"MagCUBE\u2122 - Xcalibur Smart Mapping","isPartOf":{"@id":"https:\/\/xcaliburmp.com\/pt-pt\/#website"},"datePublished":"2025-07-07T10:26:31+00:00","dateModified":"2025-07-11T07:57:41+00:00","description":"MagCUBE\u2122 otimiza a perfura\u00e7\u00e3o horizontal e direcional por meio da constru\u00e7\u00e3o de modelos IFR de alta precis\u00e3o, reduzindo os custos.","breadcrumb":{"@id":"https:\/\/xcaliburmp.com\/pt-pt\/technology\/magcube\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xcaliburmp.com\/pt-pt\/technology\/magcube\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/xcaliburmp.com\/pt-pt\/technology\/magcube\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/xcaliburmp.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"MagCUBE\u2122"}]},{"@type":"WebSite","@id":"https:\/\/xcaliburmp.com\/pt-pt\/#website","url":"https:\/\/xcaliburmp.com\/pt-pt\/","name":"Xcalibur Smart Mapping","description":"Xcalibur Smart Mapping es un l\u00edder mundial en geof\u00edsica a\u00e9rea y marina, interpretaci\u00f3n y procesamiento de datos y servicios de valor agregado.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xcaliburmp.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/xcaliburmp.com\/pt-pt\/wp-json\/wp\/v2\/technology\/9435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xcaliburmp.com\/pt-pt\/wp-json\/wp\/v2\/technology"}],"about":[{"href":"https:\/\/xcaliburmp.com\/pt-pt\/wp-json\/wp\/v2\/types\/technology"}],"wp:attachment":[{"href":"https:\/\/xcaliburmp.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=9435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}