{"id":10043,"date":"2025-07-15T11:46:34","date_gmt":"2025-07-15T09:46:34","guid":{"rendered":"https:\/\/xcaliburmp.com\/?page_id=10043"},"modified":"2025-07-15T14:28:03","modified_gmt":"2025-07-15T12:28:03","slug":"tecnologias","status":"publish","type":"page","link":"https:\/\/xcaliburmp.com\/pt-pt\/tecnologias\/","title":{"rendered":"Tecnologias"},"content":{"rendered":"\r\n<div id=\"IntroSolutions-block_f87fbfbda11a4950d487407dde7ec62d\" class=\"IntroSolutions\" >\r\n\r\n    <section class=\"hero \" id=\"heroSolutions\">\r\n        <div class=\"container\">\r\n            <span class=\"hero_kicker\">TECNOLOGIAS<\/span>\r\n            <h2 class=\"hero_title\"><p>Nosso equipamento de \u00faltima gera\u00e7\u00e3o oferece solu\u00e7\u00f5es avan\u00e7adas para explora\u00e7\u00e3o precisa de superf\u00edcies e subsuperf\u00edcies, fornecendo dados precisos e confi\u00e1veis.<\/p>\n<\/h2>\r\n            <div class=\"hero_image\"><\/div>\r\n        <\/div>\r\n    <\/section><!-- .hero -->\r\n    <div class=\"container\">\r\n        <div class=\"description\"><\/div>\r\n    <\/div>\r\n\r\n    <style>\r\n        .hero_image { background-image: url(https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/technologies-header.png); }\r\n    <\/style>\r\n\r\n            <\/div>\r\n\r\n\n\n\r\n<div id=\"RotatingText-block_e6928878cdf2ba9781ad96b9186ccd16\" class=\"RotatingText stopMovement\">\r\n    <div class=\"text\">\r\n        <p>TECNOLOGIAS<\/p>\r\n            <\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\r\n\n\n\r\n<div id=\"MappingNaturalResources-block_d04ebdfb0561d1fc8721b4a6d0e8fdc0\" class=\"MappingNaturalResources\" >\r\n\r\n    <section class=\"gallery\" id=\"gallery\">\r\n        <div class=\"wrapper\">\r\n            <div class=\"container\">\r\n                <div class=\"gallery_info\">\r\n                    <div class=\"gallery_title\"><h3>Mapeamento de recursos naturais:<br \/>\nsolu\u00e7\u00f5es geof\u00edsicas avan\u00e7adas da Xcalibur<\/h3>\n<\/div>\r\n                    <div class=\"gallery_text\"><p>Com s\u00f3lida experi\u00eancia e um hist\u00f3rico de crescimento exponencial, na Xcalibur Smart Mapping oferecemos uma ampla gama de servi\u00e7os e tecnologias avan\u00e7adas para a explora\u00e7\u00e3o e avalia\u00e7\u00e3o de recursos minerais, energ\u00e9ticos e ambientais. Com uma frota de mais de quarenta aeronaves equipadas com sistemas geof\u00edsicos, mapeamos pa\u00edses e territ\u00f3rios para identificar as propriedades das superf\u00edcies e subsuperf\u00edcies e descobrir \u00e1reas potenciais de recursos naturais, como minerais cr\u00edticos, hidrog\u00eanio ou geotermia.<\/p>\n<p>Nossa equipe multidisciplinar e altamente qualificada de especialistas utiliza tecnologias de ponta, incluindo gravimetria, magnetometria e radiometria, para interpretar esses dados inteligentes e gerar relat\u00f3rios detalhados e recomenda\u00e7\u00f5es precisas.<\/p>\n<\/div>\r\n                <\/div>\r\n                <div class=\"gallery_swiper gallery_swiper-thumbs swiper swiper-thumbs\">\r\n                    <div class=\"swiper-wrapper\">\r\n                                                    <div class=\"swiper-slide\">\r\n                                <span class=\"swiper-slide-shadow\"><\/span>\r\n                                <img decoding=\"async\" width=\"1877\" height=\"2560\" src=\"https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-1-scaled-1.webp\" class=\"\" alt=\"mapping-natural-1-scaled-1\" loading=\"lazy\" srcset=\"https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-1-scaled-1.webp 1877w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-1-scaled-1-220x300.webp 220w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-1-scaled-1-751x1024.webp 751w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-1-scaled-1-768x1047.webp 768w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-1-scaled-1-1126x1536.webp 1126w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-1-scaled-1-1502x2048.webp 1502w\" sizes=\"auto, (max-width: 1877px) 100vw, 1877px\" \/>                            <\/div>\r\n                                                    <div class=\"swiper-slide\">\r\n                                <span class=\"swiper-slide-shadow\"><\/span>\r\n                                <img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-2-scaled-1.webp\" class=\"\" alt=\"mapping-natural-2-scaled-1\" loading=\"lazy\" srcset=\"https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-2-scaled-1.webp 2560w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-2-scaled-1-300x200.webp 300w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-2-scaled-1-1024x683.webp 1024w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-2-scaled-1-768x512.webp 768w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-2-scaled-1-1536x1024.webp 1536w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-2-scaled-1-2048x1366.webp 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>                            <\/div>\r\n                                                    <div class=\"swiper-slide\">\r\n                                <span class=\"swiper-slide-shadow\"><\/span>\r\n                                <img decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-3-scaled-1.webp\" class=\"\" alt=\"mapping-natural-3-scaled-1\" loading=\"lazy\" srcset=\"https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-3-scaled-1.webp 1707w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-3-scaled-1-200x300.webp 200w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-3-scaled-1-683x1024.webp 683w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-3-scaled-1-768x1152.webp 768w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-3-scaled-1-1024x1536.webp 1024w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-3-scaled-1-1366x2048.webp 1366w\" sizes=\"auto, (max-width: 1707px) 100vw, 1707px\" \/>                            <\/div>\r\n                                                    <div class=\"swiper-slide\">\r\n                                <span class=\"swiper-slide-shadow\"><\/span>\r\n                                <img decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-4-scaled-1.webp\" class=\"\" alt=\"mapping-natural-4-scaled-1\" loading=\"lazy\" srcset=\"https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-4-scaled-1.webp 2560w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-4-scaled-1-300x225.webp 300w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-4-scaled-1-1024x768.webp 1024w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-4-scaled-1-768x576.webp 768w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-4-scaled-1-1536x1152.webp 1536w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-4-scaled-1-2048x1536.webp 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>                            <\/div>\r\n                                            <\/div>\r\n                <\/div>\r\n            <\/div>\r\n            <div class=\"gallery_swiper gallery_swiper-expand swiper swiper-expand\" id=\"gallerySwiper\">\r\n                <div class=\"swiper-wrapper\">\r\n                                            <div class=\"swiper-slide\">\r\n                            <img decoding=\"async\" width=\"1877\" height=\"2560\" src=\"https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-1-scaled-1.webp\" class=\"\" alt=\"mapping-natural-1-scaled-1\" loading=\"lazy\" srcset=\"https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-1-scaled-1.webp 1877w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-1-scaled-1-220x300.webp 220w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-1-scaled-1-751x1024.webp 751w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-1-scaled-1-768x1047.webp 768w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-1-scaled-1-1126x1536.webp 1126w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-1-scaled-1-1502x2048.webp 1502w\" sizes=\"auto, (max-width: 1877px) 100vw, 1877px\" \/>                        <\/div>\r\n                                            <div class=\"swiper-slide\">\r\n                            <img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-2-scaled-1.webp\" class=\"\" alt=\"mapping-natural-2-scaled-1\" loading=\"lazy\" srcset=\"https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-2-scaled-1.webp 2560w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-2-scaled-1-300x200.webp 300w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-2-scaled-1-1024x683.webp 1024w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-2-scaled-1-768x512.webp 768w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-2-scaled-1-1536x1024.webp 1536w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-2-scaled-1-2048x1366.webp 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>                        <\/div>\r\n                                            <div class=\"swiper-slide\">\r\n                            <img decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-3-scaled-1.webp\" class=\"\" alt=\"mapping-natural-3-scaled-1\" loading=\"lazy\" srcset=\"https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-3-scaled-1.webp 1707w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-3-scaled-1-200x300.webp 200w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-3-scaled-1-683x1024.webp 683w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-3-scaled-1-768x1152.webp 768w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-3-scaled-1-1024x1536.webp 1024w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-3-scaled-1-1366x2048.webp 1366w\" sizes=\"auto, (max-width: 1707px) 100vw, 1707px\" \/>                        <\/div>\r\n                                            <div class=\"swiper-slide\">\r\n                            <img decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-4-scaled-1.webp\" class=\"\" alt=\"mapping-natural-4-scaled-1\" loading=\"lazy\" srcset=\"https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-4-scaled-1.webp 2560w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-4-scaled-1-300x225.webp 300w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-4-scaled-1-1024x768.webp 1024w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-4-scaled-1-768x576.webp 768w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-4-scaled-1-1536x1152.webp 1536w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/mapping-natural-4-scaled-1-2048x1536.webp 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>                        <\/div>\r\n                                    <\/div>\r\n                <div class=\"swiper-button-next\"><\/div>\r\n                <div class=\"swiper-button-prev\"><\/div>\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"trick\"><\/div>\r\n    <\/section><!-- .gallery -->\r\n\r\n                <\/div>\r\n\r\n\r\n<script src=\"https:\/\/xcaliburmp.com\/wp-content\/themes\/xcalibur\/assets\/js\/swiper.min.js\"><\/script>\r\n<!--<script src=\"https:\/\/xcaliburmp.com\/wp-content\/themes\/xcalibur\/assets\/js\/main.js\"><\/script>-->\r\n\n\n\r\n<div id=\"OurAirborneTechnologies-block_a2d87ae913227c7c788c046180331173\" class=\"OurAirborneTechnologies\">\r\n    <div class=\"overlay\"><\/div>\r\n        <div class=\"container\">\r\n            <div class=\"ourtec\">\r\n                <div class=\"wrapper\">\r\n                    <div class=\"col\">\r\n                        <div class=\"title\"><p>NOSSAS TECNOLOGIAS AEROTRANSPORTADAS<\/p>\n<\/div>\r\n                    <\/div>\r\n                    <div class=\"col\">\r\n                        <div class=\"desc\"><p>Nossas tecnologias inovadoras permitem uma explora\u00e7\u00e3o eficiente de alvos por meio da aquisi\u00e7\u00e3o, an\u00e1lise e interpreta\u00e7\u00e3o de dados aerotransportados, reduzindo o impacto ambiental.<\/p>\n<\/div>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n\r\n            <div class=\"contentData\">\r\n                <div class=\"btnsVideo\">\r\n                    <div class=\"contAbsolute\">\r\n                        <video class=\"airtech-video\" autoplay muted loop playsinline preload=\"auto\" playsinline>\r\n                            <source src=\"https:\/\/xcaliburmp.com\/wp-content\/themes\/xcalibur\/assets\/images\/airborne-technologies-video.mp4\" type=\"video\/mp4\">\r\n                        <\/video>\r\n                        <div class=\"selectors\">\r\n                                                            <div class=\"lineSelect\">\r\n                                    <div class=\"selectionsData active\" data-target=\"0\">\r\n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"32\" height=\"32\" viewBox=\"0 0 32 32\" fill=\"none\">\r\n                                            <rect x=\"0.142857\" y=\"0.142857\" width=\"31.7143\" height=\"31.7143\" rx=\"15.8571\" fill=\"#451B17\"\/>\r\n                                            <rect x=\"0.142857\" y=\"0.142857\" width=\"31.7143\" height=\"31.7143\" rx=\"15.8571\" stroke=\"#FFF\" stroke-width=\"0.285714\"\/>\r\n                                            <circle opacity=\"0.2\" cx=\"16.0006\" cy=\"16.0006\" r=\"7.14118\" fill=\"#FFF\"\/>\r\n                                            <circle cx=\"15.9807\" cy=\"15.9827\" r=\"3.34989\" fill=\"#FFF\"\/>\r\n                                        <\/svg>\r\n                                        <span>Magnetometria e Radiometria A\u00e9reas<\/span>\r\n                                    <\/div>\r\n                                    <div class=\"line\"><\/div>\r\n                                <\/div>\r\n                                                            <div class=\"lineSelect\">\r\n                                    <div class=\"selectionsData \" data-target=\"1\">\r\n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"32\" height=\"32\" viewBox=\"0 0 32 32\" fill=\"none\">\r\n                                            <rect x=\"0.142857\" y=\"0.142857\" width=\"31.7143\" height=\"31.7143\" rx=\"15.8571\" fill=\"#451B17\"\/>\r\n                                            <rect x=\"0.142857\" y=\"0.142857\" width=\"31.7143\" height=\"31.7143\" rx=\"15.8571\" stroke=\"#FFF\" stroke-width=\"0.285714\"\/>\r\n                                            <circle opacity=\"0.2\" cx=\"16.0006\" cy=\"16.0006\" r=\"7.14118\" fill=\"#FFF\"\/>\r\n                                            <circle cx=\"15.9807\" cy=\"15.9827\" r=\"3.34989\" fill=\"#FFF\"\/>\r\n                                        <\/svg>\r\n                                        <span>Eletromagnetismo A\u00e9reo<\/span>\r\n                                    <\/div>\r\n                                    <div class=\"line\"><\/div>\r\n                                <\/div>\r\n                                                            <div class=\"lineSelect\">\r\n                                    <div class=\"selectionsData \" data-target=\"2\">\r\n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"32\" height=\"32\" viewBox=\"0 0 32 32\" fill=\"none\">\r\n                                            <rect x=\"0.142857\" y=\"0.142857\" width=\"31.7143\" height=\"31.7143\" rx=\"15.8571\" fill=\"#451B17\"\/>\r\n                                            <rect x=\"0.142857\" y=\"0.142857\" width=\"31.7143\" height=\"31.7143\" rx=\"15.8571\" stroke=\"#FFF\" stroke-width=\"0.285714\"\/>\r\n                                            <circle opacity=\"0.2\" cx=\"16.0006\" cy=\"16.0006\" r=\"7.14118\" fill=\"#FFF\"\/>\r\n                                            <circle cx=\"15.9807\" cy=\"15.9827\" r=\"3.34989\" fill=\"#FFF\"\/>\r\n                                        <\/svg>\r\n                                        <span>Gradiometria Gravitacional A\u00e9rea<\/span>\r\n                                    <\/div>\r\n                                    <div class=\"line\"><\/div>\r\n                                <\/div>\r\n                                                            <div class=\"lineSelect\">\r\n                                    <div class=\"selectionsData \" data-target=\"3\">\r\n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"32\" height=\"32\" viewBox=\"0 0 32 32\" fill=\"none\">\r\n                                            <rect x=\"0.142857\" y=\"0.142857\" width=\"31.7143\" height=\"31.7143\" rx=\"15.8571\" fill=\"#451B17\"\/>\r\n                                            <rect x=\"0.142857\" y=\"0.142857\" width=\"31.7143\" height=\"31.7143\" rx=\"15.8571\" stroke=\"#FFF\" stroke-width=\"0.285714\"\/>\r\n                                            <circle opacity=\"0.2\" cx=\"16.0006\" cy=\"16.0006\" r=\"7.14118\" fill=\"#FFF\"\/>\r\n                                            <circle cx=\"15.9807\" cy=\"15.9827\" r=\"3.34989\" fill=\"#FFF\"\/>\r\n                                        <\/svg>\r\n                                        <span>Gravimetria Escalar Aerotransportada<\/span>\r\n                                    <\/div>\r\n                                    <div class=\"line\"><\/div>\r\n                                <\/div>\r\n                                                    <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n                <div class=\"contents\">\r\n                                            <div class=\"contentInfo active\" data-target=\"0\">\r\n                            <img decoding=\"async\" class=\"closeModal\" src=\"https:\/\/xcaliburmp.com\/wp-content\/themes\/xcalibur\/assets\/images\/close-modal.svg\" alt=\"arrow\">\r\n                            <div class=\"title\">Magnetometria e Radiometria A\u00e9reas<\/div>\r\n                            <div class=\"contScroll\">\r\n                                <div class=\"scrollText\">\r\n                                    <div class=\"text\"><p>A Xcalibur Smart Mapping oferece servi\u00e7os l\u00edderes de mercado em Magnetometria e Radiometria Aerotransportadas (MAG\/RAD) e levantamentos opcionais de gravidade escalar para mapeamento geol\u00f3gico e explora\u00e7\u00e3o mineral. Os levantamentos s\u00e3o geralmente realizados com aeronaves personalizadas de baixo voo, para m\u00e1xima efici\u00eancia e dados geof\u00edsicos de ultra-alta resolu\u00e7\u00e3o. A \u00fanica limita\u00e7\u00e3o da altura do voo \u00e9 a altura da vegeta\u00e7\u00e3o e das estruturas artificiais.<\/p>\n<p>A Xcalibur Smart Mapping tamb\u00e9m oferece aplica\u00e7\u00f5es espec\u00edficas com helic\u00f3pteros para \u00e1reas de dif\u00edcil acesso, utilizando magnet\u00f4metros montados na ponta do boom e pacotes de cristais radiom\u00e9tricos para adquirir dados magn\u00e9ticos e radiom\u00e9tricos de ultra-alta resolu\u00e7\u00e3o em terrenos acidentados.<\/p>\n<\/div>\r\n                                <\/div>\r\n                                                                    <div class=\"boxed-text\">\r\n                                        <div class=\"text\"><p><em>The associated technologies are mentioned below:<\/em><\/p>\n<\/div>\r\n                                                                                    <div class=\"fleets\">\r\n                                                <ul>\r\n                                                                                                            <li>MIDAS\u00ae<\/li>\r\n                                                                                                            <li>XMAG\u00ae<\/li>\r\n                                                                                                    <\/ul>\r\n                                            <\/div>\r\n                                                                            <\/div>\r\n                                                            <\/div>\r\n                            <a class=\"cta_button button\" href=\"https:\/\/xcaliburmp.com\/pt-pt\/technology\/magnetometria-e-radiometria-aereas\/\" target=\"_self\">MAIS INFORMA\u00c7\u00d5ES<\/a>\r\n                        <\/div>\r\n                                            <div class=\"contentInfo \" data-target=\"1\">\r\n                            <img decoding=\"async\" class=\"closeModal\" src=\"https:\/\/xcaliburmp.com\/wp-content\/themes\/xcalibur\/assets\/images\/close-modal.svg\" alt=\"arrow\">\r\n                            <div class=\"title\">Eletromagnetismo A\u00e9reo<\/div>\r\n                            <div class=\"contScroll\">\r\n                                <div class=\"scrollText\">\r\n                                    <div class=\"text\"><p>A Xcalibur Smart Mapping oferece uma variedade de tecnologias de eletromagnetismo a\u00e9reo (AEM) l\u00edderes do setor para mapeamento de condutividade e detec\u00e7\u00e3o de alvos.<\/p>\n<p>Seus sistemas AEM s\u00e3o projetados para diferentes aplica\u00e7\u00f5es, fornecendo as melhores solu\u00e7\u00f5es t\u00e9cnicas e comerciais. Esses sistemas podem captar imagens de alvos na superf\u00edcie ou em profundidades de at\u00e9 600 metros, fornecendo dados eletromagn\u00e9ticos, magn\u00e9ticos, radiom\u00e9tricos e de gravidade escalar simultaneamente. Os sistemas AEM da Xcalibur s\u00e3o propriet\u00e1rios e passaram por extensa pesquisa e desenvolvimento.<\/p>\n<p>O sistema TEMPEST\u00ae \u00e9 um sistema AEM de asa fixa com alta resolu\u00e7\u00e3o e largura de banda ampla. O HeliTEM\u00ae \u00e9 um sistema AEM de helic\u00f3ptero no dom\u00ednio do tempo com sensibilidade aprimorada, enquanto o RESOLVE\u00ae oferece a maior resolu\u00e7\u00e3o para medi\u00e7\u00f5es de condutividade pr\u00f3ximas \u00e0 superf\u00edcie.<\/p>\n<\/div>\r\n                                <\/div>\r\n                                                                    <div class=\"boxed-text\">\r\n                                        <div class=\"text\"><p><em>As tecnologias associadas s\u00e3o mencionadas abaixo:<\/em><\/p>\n<\/div>\r\n                                                                                    <div class=\"fleets\">\r\n                                                <ul>\r\n                                                                                                            <li>TEMPEST\u00ae<\/li>\r\n                                                                                                            <li>HeliTEM\u00ae<\/li>\r\n                                                                                                            <li>RESOLVE\u00ae<\/li>\r\n                                                                                                    <\/ul>\r\n                                            <\/div>\r\n                                                                            <\/div>\r\n                                                            <\/div>\r\n                            <a class=\"cta_button button\" href=\"https:\/\/xcaliburmp.com\/pt-pt\/technology\/eletromagnetismo-aereo\/\" target=\"_self\">MAIS INFORMA\u00c7\u00d5ES<\/a>\r\n                        <\/div>\r\n                                            <div class=\"contentInfo \" data-target=\"2\">\r\n                            <img decoding=\"async\" class=\"closeModal\" src=\"https:\/\/xcaliburmp.com\/wp-content\/themes\/xcalibur\/assets\/images\/close-modal.svg\" alt=\"arrow\">\r\n                            <div class=\"title\">Gradiometria Gravitacional A\u00e9rea<\/div>\r\n                            <div class=\"contScroll\">\r\n                                <div class=\"scrollText\">\r\n                                    <div class=\"text\"><p>A Xcalibur Smart Mapping \u00e9 l\u00edder em tecnologia FALCON\u00ae Gradiometria Gravitacional A\u00e9rea (AGG), fornecendo solu\u00e7\u00f5es de gravimetria de alta resolu\u00e7\u00e3o e qualidade para mapeamento e detec\u00e7\u00e3o de alvos em diversos setores.<\/p>\n<p>Desenvolvido em colabora\u00e7\u00e3o com o Lockheed Martin, o FALCON\u00ae AGG \u00e9 especificamente projetado para ambientes a\u00e9reos desafiadores. A Xcalibur Smart Mapping opera seis sistemas FALCON\u00ae globalmente em plataformas de asa fixa e helic\u00f3ptero, oferecendo a mais alta qualidade de dados e especifica\u00e7\u00f5es de ru\u00eddo mais baixas.<\/p>\n<p>Os levantamentos cobrem 100% da \u00e1rea, incluindo topografia, vegeta\u00e7\u00e3o e \u00e1reas restritas. Dados magn\u00e9ticos s\u00e3o adquiridos como padr\u00e3o e dados radiom\u00e9tricos podem ser inclu\u00eddos opcionalmente.<\/p>\n<p>A fam\u00edlia FALCON\u00ae oferece diferentes op\u00e7\u00f5es de sistema adaptadas para atender \u00e0s necessidades de explora\u00e7\u00e3o, garantindo opera\u00e7\u00f5es eficientes com impacto ambiental m\u00ednimo.<\/p>\n<\/div>\r\n                                <\/div>\r\n                                                                    <div class=\"boxed-text\">\r\n                                        <div class=\"text\"><p><em>As tecnologias associadas s\u00e3o mencionadas abaixo:<\/em><\/p>\n<\/div>\r\n                                                                                    <div class=\"fleets\">\r\n                                                <ul>\r\n                                                                                                            <li>FALCON\u00ae AGG<\/li>\r\n                                                                                                            <li>HeliFALCON\u00ae AGG<\/li>\r\n                                                                                                    <\/ul>\r\n                                            <\/div>\r\n                                                                            <\/div>\r\n                                                            <\/div>\r\n                            <a class=\"cta_button button\" href=\"https:\/\/xcaliburmp.com\/pt-pt\/technology\/gradiometria-gravitacional-aerea\/\" target=\"_self\">MAIS INFORMA\u00c7\u00d5ES<\/a>\r\n                        <\/div>\r\n                                            <div class=\"contentInfo \" data-target=\"3\">\r\n                            <img decoding=\"async\" class=\"closeModal\" src=\"https:\/\/xcaliburmp.com\/wp-content\/themes\/xcalibur\/assets\/images\/close-modal.svg\" alt=\"arrow\">\r\n                            <div class=\"title\">Gravimetria Escalar Aerotransportada<\/div>\r\n                            <div class=\"contScroll\">\r\n                                <div class=\"scrollText\">\r\n                                    <div class=\"text\"><p>As medi\u00e7\u00f5es de gravidade escalar t\u00eam diversas aplica\u00e7\u00f5es em mapeamento geol\u00f3gico, explora\u00e7\u00e3o de petr\u00f3leo e g\u00e1s e estudos geod\u00e9sicos. A Xcalibur Smart Mapping oferece o grav\u00edmetro escalar iCORUS-iX\u2122, um dispositivo \u00fanico que adquire dados de gravimetria sem a necessidade de uma plataforma estabilizada. Este sistema exclusivo fornece dados com metade dos n\u00edveis de ru\u00eddo de outros sistemas dispon\u00edveis comercialmente. O iCORUS-iX\u2122 \u00e9 compacto e robusto, permitindo a aquisi\u00e7\u00e3o de dados de gravimetria escalar de alta qualidade simultaneamente com levantamentos magn\u00e9ticos, eletromagn\u00e9ticos ou de gradiometria de gravidade, mesmo em condi\u00e7\u00f5es turbulentas. O iCORUS-iX\u2122 pode alcan\u00e7ar uma qualidade de dados de gravidade &lt;1.0mGal com uma resolu\u00e7\u00e3o de 3km quando voado com espa\u00e7amentos de linhas mais amplos, e conjuntos de dados de alta resolu\u00e7\u00e3o podem ser obtidos por meio de oversampling com espa\u00e7amentos de linhas mais estreitos.<\/p>\n<\/div>\r\n                                <\/div>\r\n                                                                    <div class=\"boxed-text\">\r\n                                        <div class=\"text\"><p><em>As tecnologias associadas s\u00e3o mencionadas abaixo:<\/em><\/p>\n<\/div>\r\n                                                                                    <div class=\"fleets\">\r\n                                                <ul>\r\n                                                                                                            <li>iCORUS-iX\u2122<\/li>\r\n                                                                                                    <\/ul>\r\n                                            <\/div>\r\n                                                                            <\/div>\r\n                                                            <\/div>\r\n                            <a class=\"cta_button button\" href=\"https:\/\/xcaliburmp.com\/pt-pt\/technology\/gravimetria-escalar-aerotransportada\/\" target=\"_self\">MAIS INFORMA\u00c7\u00d5ES<\/a>\r\n                        <\/div>\r\n                                    <\/div>\r\n            <\/div>\r\n        <\/div>\r\n\r\n<\/div>\r\n\r\n\n\n\r\n<div id=\"BackgroundImageContent-block_48822270c2c3f75633ff5c7ee5441cad\" class=\"BackgroundImageContent\" style=\"background-color:#451B17\">\r\n\r\n    <div class=\"imageBG\" style=\"background-image:url('https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/geospatial.webp')\">\r\n        <div class=\"content v2\">\r\n                            <div class=\"title\"><p>Tecnologias <span style=\"color: #ff3300;\">Geoespaciais<\/span><\/p>\n<\/div>\r\n                <div class=\"contentBox\">\r\n                    <div class=\"text\">\r\n                        <p>Na Xcalibur Smart Mapping, oferecemos solu\u00e7\u00f5es geoespaciais que v\u00e3o desde a an\u00e1lise espec\u00edfica de dados at\u00e9 o design completo de sistemas, aproveitando nossa experi\u00eancia em GIS e sensoriamento remoto para setores como minera\u00e7\u00e3o, energia, meio ambiente e muito mais.<\/p>\n                    <\/div>\r\n                                            <a class=\"cta_button button\" href=\"https:\/\/xcaliburmp.com\/pt-pt\/technology\/tecnologias-geoespaciais\/\" target=\"_self\" title=\"VER MAIS\">VER MAIS<\/a>\r\n                                    <\/div>\r\n                    <\/div>\r\n    <\/div>\r\n\r\n<\/div>\n\n\r\n<div id=\"OurOtherTechnologies-block_4afcde08f3fd27451ef0456968b67b5d\" class=\"OurOtherTechnologies\">\r\n\r\n        <div class=\"container\">\r\n            <div class=\"ourtec\">\r\n                <div class=\"wrapper\">\r\n                    <div class=\"col\">\r\n                        <div class=\"title\"><p>Maximizando os dados geof\u00edsicos com <span style=\"color: #ff3300;\">solu\u00e7\u00f5es avan\u00e7adas de software<\/span><\/p>\n<\/div>\r\n                    <\/div>\r\n                    <div class=\"col\">\r\n                        <div class=\"desc\"><p>Na Xcalibur Smart Mapping, desenvolvemos e fornecemos solu\u00e7\u00f5es de software especificamente projetadas para maximizar o valor dos dados geof\u00edsicos e facilitar an\u00e1lises aprofundadas em levantamentos a\u00e9reos. Nosso software avan\u00e7ado permite a captura, o processamento e a visualiza\u00e7\u00e3o precisos de dados geoespaciais, oferecendo aos nossos clientes informa\u00e7\u00f5es claras e confi\u00e1veis para a tomada de decis\u00f5es estrat\u00e9gicas.<\/p>\n<\/div>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n            <div class=\"technologies\">\r\n                                <div class=\"technology\">\r\n                    <div class=\"info\">\r\n                        <div class=\"upData\">\r\n                            <div class=\"title\">MagCUBE\u2122<\/div>\r\n                            <div class=\"text\"><p>MagCUBE\u2122 converte anomalias magn\u00e9ticas em campos vetoriais de subsuperf\u00edcie, aumentando a precis\u00e3o e a efici\u00eancia da perfura\u00e7\u00e3o com refer\u00eancias geomagn\u00e9ticas precisas para o posicionamento ideal do po\u00e7o.<\/p>\n<\/div>\r\n                        <\/div>\r\n                        <div class=\"down\">\r\n                                                            <a class=\"cta_button button\" href=\"https:\/\/xcaliburmp.com\/pt-pt\/technology\/magcube\/\" target=\"\">VER MAIS<\/a>\r\n                                                                                        <div class=\"contImg\">\r\n                                    <div class=\"image\">\r\n                                        <img decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/05\/ChatGPT-Image-27-may-2025-14_47_13-300x200.png\" class=\"attachment-medium size-medium\" alt=\"ChatGPT Image 27 may 2025, 14_47_13\" loading=\"lazy\" srcset=\"https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/05\/ChatGPT-Image-27-may-2025-14_47_13-300x200.png 300w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/05\/ChatGPT-Image-27-may-2025-14_47_13-1024x683.png 1024w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/05\/ChatGPT-Image-27-may-2025-14_47_13-768x512.png 768w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/05\/ChatGPT-Image-27-may-2025-14_47_13.png 1536w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                    <\/div>\r\n                                <\/div>\r\n                            \r\n                        <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n                                <div class=\"technology\">\r\n                    <div class=\"info\">\r\n                        <div class=\"upData\">\r\n                            <div class=\"title\">(LCT) Software de gravidade, gradiometria e magnetismo<\/div>\r\n                            <div class=\"text\"><p>Oferecemos solu\u00e7\u00f5es de gravidade e magnetismo com o software LCT para modelagem 2D\/3D, invers\u00e3o conjunta, processamento de dados e servi\u00e7os especializados de consultoria.<\/p>\n<\/div>\r\n                        <\/div>\r\n                        <div class=\"down\">\r\n                                                            <a class=\"cta_button button\" href=\"https:\/\/xcaliburmp.com\/pt-pt\/technology\/software-de-gravimetria-de-gradiente-e-magnetometria\/\" target=\"\">VER MAIS<\/a>\r\n                                                                                        <div class=\"contImg\">\r\n                                    <div class=\"image\">\r\n                                        <img decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/06\/wild_rift-300x169-1.png\" class=\"attachment-medium size-medium\" alt=\"wild_rift-300x169\" loading=\"lazy\" \/>                                    <\/div>\r\n                                <\/div>\r\n                            \r\n                        <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n                                <div class=\"technology\">\r\n                    <div class=\"info\">\r\n                        <div class=\"upData\">\r\n                            <div class=\"title\">Smart GeoMap<\/div>\r\n                            <div class=\"text\"><p>Smart GeoMap integra e visualiza dados geocient\u00edficos de \u00e1reas como geologia e geof\u00edsica, permitindo an\u00e1lises personalizadas, modelagem preditiva e tomada de decis\u00f5es informadas com ferramentas flex\u00edveis.<\/p>\n<\/div>\r\n                        <\/div>\r\n                        <div class=\"down\">\r\n                                                            <a class=\"cta_button button\" href=\"https:\/\/youtu.be\/nCf7UADL_40?si=Y9hWamRLNJ9UTV6l\" target=\"\">VER VIDEO<\/a>\r\n                                                                                        <div class=\"contImg\">\r\n                                    <div class=\"image\">\r\n                                        <img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/xcaliburmp.com\/wp-content\/uploads\/2024\/04\/usgs-nSOZqxCIEAs-unsplash-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"usgs-nSOZqxCIEAs-unsplash\" loading=\"lazy\" srcset=\"https:\/\/xcaliburmp.com\/wp-content\/uploads\/2024\/04\/usgs-nSOZqxCIEAs-unsplash-300x300.jpg 300w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2024\/04\/usgs-nSOZqxCIEAs-unsplash-1024x1024.jpg 1024w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2024\/04\/usgs-nSOZqxCIEAs-unsplash-150x150.jpg 150w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2024\/04\/usgs-nSOZqxCIEAs-unsplash-768x768.jpg 768w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2024\/04\/usgs-nSOZqxCIEAs-unsplash-1536x1536.jpg 1536w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2024\/04\/usgs-nSOZqxCIEAs-unsplash-2048x2048.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                    <\/div>\r\n                                <\/div>\r\n                            \r\n                        <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n                                <div class=\"technology\">\r\n                    <div class=\"info\">\r\n                        <div class=\"upData\">\r\n                            <div class=\"title\">Data Visualization<\/div>\r\n                            <div class=\"text\"><p>Na Xcalibur Smart Mapping, somos especializados em visualiza\u00e7\u00e3o de dados, transformando dados georreferenciados em insights acion\u00e1veis para os setores de energia, minera\u00e7\u00e3o, alertas de riscos e geomarketing, apoiando a tomada de decis\u00f5es estrat\u00e9gicas.<\/p>\n<\/div>\r\n                        <\/div>\r\n                        <div class=\"down\">\r\n                                                            <a class=\"cta_button button\" href=\"https:\/\/xcaliburmp.com\/pt-pt\/research-development-innovation\/#especialistas-em-visualizacao\" target=\"\">VER MAIS<\/a>\r\n                                                                                        <div class=\"contImg\">\r\n                                    <div class=\"image\">\r\n                                        <img decoding=\"async\" width=\"300\" height=\"168\" src=\"https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/04\/746b5c0696671a540a374bdd79f7d1ce-300x168.png\" class=\"attachment-medium size-medium\" alt=\"746b5c0696671a540a374bdd79f7d1ce\" loading=\"lazy\" srcset=\"https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/04\/746b5c0696671a540a374bdd79f7d1ce-300x168.png 300w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/04\/746b5c0696671a540a374bdd79f7d1ce-1024x574.png 1024w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/04\/746b5c0696671a540a374bdd79f7d1ce-768x430.png 768w, https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/04\/746b5c0696671a540a374bdd79f7d1ce.png 1456w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                    <\/div>\r\n                                <\/div>\r\n                            \r\n                        <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n                            <\/div>\r\n            <div class=\"loadMore\">\r\n                <span>VER MAIS<\/span>\r\n                <img decoding=\"async\" class=\"iconPlus\" src=\"https:\/\/xcaliburmp.com\/wp-content\/themes\/xcalibur\/assets\/images\/plusi-icon.svg\" alt=\"icon\" \/>\r\n            <\/div>\r\n        <\/div>\r\n\r\n<\/div>\r\n\r\n\n\n\r\n<div id=\"nossa-frota\" class=\"v2 OurFleet\" >\r\n\r\n    \r\n        <section class=\"our-fleet\" id=\"our-fleet\">\r\n            <div class=\"container\">\r\n                <div data-aos=\"fade-right\" class=\"fleetRow\">\r\n                    <div class=\"fleet-col\">\r\n                        <div class=\"titulo\">\r\n                            NOSSA FROTA                        <\/div>\r\n                    <\/div>\r\n                    <div class=\"fleet-col \">\r\n                        <div class=\"description\">\r\n                            <p>Somos reconhecidos como l\u00edderes do setor, distinguidos pela escala e versatilidade de nossa frota, o que nos permite executar projetos em todo o mundo.<\/p>\n                        <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n                <div class=\"descriptionBottom\">\r\n                    <p>Na Xcalibur Smart Mapping operamos 45 aeronaves tecnologicamente adaptadas, incluindo avi\u00f5es e helic\u00f3pteros. Tr\u00eas delas s\u00e3o dedicadas ao treinamento, garantindo os mais altos padr\u00f5es de seguran\u00e7a e profici\u00eancia operacional entre os membros da equipe.<\/p>\n                <\/div>\r\n                <div class=\"fleetContainer\">\r\n                                            <div class=\"fleetContent\">\r\n                            <div id=\"hyper-3d-6\" class=\"hyper-3d-container\"><hyper-3d high-quality=\"\" draco-path=\"https:\/\/xcaliburmp.com\/wp-content\/plugins\/codecanyon-U9Ff1GJu-hyper-3d-model-and-panorama-viewer-for-wordpress\/assets\/draco\/\" onload=\"hyper3dLoad(this);\" loading=\"auto\" ratio=\"1:1\" direction=\"-131.5\" elevation=\"10\" center=\"0 0.0127643722 0\" ambient-light=\"0.6\" camera-light=\"0.15\" point-light=\"0.7\" point-light-position=\"0.047424 0.072673 0\" reflection=\"0.1\" reflection-softness=\"0.1\" src=\"https:\/\/xcaliburmp.com\/wp-content\/uploads\/2025\/05\/pacific2.obj?v=1747065232729\" elevation-limit=\"-90 90\" zoom=\"2\" class=\"\"><\/hyper-3d><div class=\"hyper-3d-content hyper-3d-on-top\" style=\"display:none\"><div><\/div><span class=\"hyper-3d-close\"><\/span><\/div><\/div><script type=\"module\" src=\"https:\/\/xcaliburmp.com\/wp-content\/plugins\/codecanyon-U9Ff1GJu-hyper-3d-model-and-panorama-viewer-for-wordpress\/assets\/hyper-3d.min.js\"><\/script>                            <div class=\"textCta\">\r\n                                <div class=\"titleDescription\">\r\n                                    <div class=\"fleetpreNumber\">SOMOS PROPRIET\u00c1RIOS DE<\/div>\r\n                                    <div class=\"fleetContentNumber\">04<\/div>\r\n                                    <h2 class=\"fleetContentTitle\">PAC 750<\/h2>\r\n                                    <div class=\"fleetContentDescription\"><p>A PAC750, com design robusto e motor PT6-34, destaca-se em levantamentos geof\u00edsicos de baixa altitude a partir de pistas curtas e irregulares, suporta assento para observador e permite a instala\u00e7\u00e3o de sensores magn\u00e9ticos e radiom\u00e9tricos para coleta de dados de alta qualidade.<\/p>\n<\/div>\r\n                                <\/div>\r\n                                <a class=\"cta_button button\" href=\"https:\/\/xcaliburmp.com\/pt-pt\/fleet\/pac-750\/\" target=\"_self\" title=\"VER MAIS\">VER MAIS<\/a>\r\n                            <\/div>\r\n                        <\/div>\r\n                                            <div class=\"fleetContent\">\r\n                            <div id=\"hyper-3d-2\" class=\"hyper-3d-container\"><hyper-3d high-quality=\"\" draco-path=\"https:\/\/xcaliburmp.com\/wp-content\/plugins\/codecanyon-U9Ff1GJu-hyper-3d-model-and-panorama-viewer-for-wordpress\/assets\/draco\/\" onload=\"hyper3dLoad(this);\" loading=\"auto\" ratio=\"1:1\" direction=\"-131\" elevation=\"10\" center=\"0 0.01867 0\" ambient-light=\"0.2\" camera-light=\"0.2\" point-light=\"0.2\" point-light-position=\"0 0.072646 0\" reflection=\"0.2\" reflection-softness=\"0\" src=\"https:\/\/xcaliburmp.com\/wp-content\/uploads\/2024\/06\/AT502C.obj?v=1718012009878\" elevation-limit=\"-90 90\" zoom=\"1.3\" class=\"\"><\/hyper-3d><div class=\"hyper-3d-content hyper-3d-on-top\" style=\"display:none\"><div><\/div><span class=\"hyper-3d-close\"><\/span><\/div><\/div><script type=\"module\" src=\"https:\/\/xcaliburmp.com\/wp-content\/plugins\/codecanyon-U9Ff1GJu-hyper-3d-model-and-panorama-viewer-for-wordpress\/assets\/hyper-3d.min.js\"><\/script>                            <div class=\"textCta\">\r\n                                <div class=\"titleDescription\">\r\n                                    <div class=\"fleetpreNumber\">SOMOS PROPRIET\u00c1RIOS DE<\/div>\r\n                                    <div class=\"fleetContentNumber\">15<\/div>\r\n                                    <h2 class=\"fleetContentTitle\">Air Tractor (502B, 504)<\/h2>\r\n                                    <div class=\"fleetContentDescription\"><p>O Air Tractor destaca-se em ambientes dif\u00edceis gra\u00e7as ao seu design est\u00e1vel, trem de pouso com absor\u00e7\u00e3o de impacto, otimiza\u00e7\u00e3o para voos a baixa altitude e recursos avan\u00e7ados de seguran\u00e7a, oferecendo desempenho econ\u00f4mico em levantamentos de alta resolu\u00e7\u00e3o com prote\u00e7\u00e3o excepcional ao piloto.<\/p>\n<\/div>\r\n                                <\/div>\r\n                                <a class=\"cta_button button\" href=\"https:\/\/xcaliburmp.com\/pt-pt\/fleet\/air-tractor-502b-504\/\" target=\"_self\" title=\"VER MAIS\">VER MAIS<\/a>\r\n                            <\/div>\r\n                        <\/div>\r\n                                            <div class=\"fleetContent\">\r\n                            <div id=\"hyper-3d-3\" class=\"hyper-3d-container\"><hyper-3d high-quality=\"\" draco-path=\"https:\/\/xcaliburmp.com\/wp-content\/plugins\/codecanyon-sH7aulc3-hyper-3d-model-and-panorama-viewer-for-wordpress\/assets\/draco\/\" onload=\"hyper3dLoad(this);\" loading=\"auto\" ratio=\"1:1\" direction=\"-45\" elevation=\"45\" center=\"0.00046 0.010788 0\" ambient-light=\"0.7\" camera-light=\"0.25\" point-light=\"0.25\" point-light-position=\"0 0.065779 0\" reflection=\"0.15\" reflection-softness=\"0\" src=\"https:\/\/xcaliburmp.com\/wp-content\/uploads\/2024\/06\/cessna-4.obj?v=1717573887345\" elevation-limit=\"-90 90\" zoom=\"1.3\" class=\"\"><\/hyper-3d><div class=\"hyper-3d-content hyper-3d-on-top\" style=\"display:none\"><div><\/div><span class=\"hyper-3d-close\"><\/span><\/div><\/div><script type=\"module\" src=\"https:\/\/xcaliburmp.com\/wp-content\/plugins\/codecanyon-U9Ff1GJu-hyper-3d-model-and-panorama-viewer-for-wordpress\/assets\/hyper-3d.min.js\"><\/script>                            <div class=\"textCta\">\r\n                                <div class=\"titleDescription\">\r\n                                    <div class=\"fleetpreNumber\">SOMOS PROPRIET\u00c1RIOS DE<\/div>\r\n                                    <div class=\"fleetContentNumber\">22<\/div>\r\n                                    <h2 class=\"fleetContentTitle\">Cessna 208B Grand Caravan \u2013 Cessna 208B Supervan 900<\/h2>\r\n                                    <div class=\"fleetContentDescription\"><p>O Cessna 208B Grand Caravan e o Supervan 900 s\u00e3o aeronaves confi\u00e1veis para levantamentos; o Grand Caravan \u00e9 ideal para o FALCON\u00ae AGG, enquanto o potente Supervan 900 se destaca nos projetos TEMPEST\u00ae AEM.<\/p>\n<\/div>\r\n                                <\/div>\r\n                                <a class=\"cta_button button\" href=\"https:\/\/xcaliburmp.com\/pt-pt\/fleet\/cessna-208b-grand-caravan-cessna-208b-supervan-900\/\" target=\"_self\" title=\"VER MAIS\">VER MAIS<\/a>\r\n                            <\/div>\r\n                        <\/div>\r\n                                    <\/div>\r\n            <\/div>\r\n        <\/section>\r\n\r\n    \r\n<\/div>\n\n\r\n<div id=\"ContactUs-block_bf7f2f06a3296b03fbae7e555d53e86c\" class=\"ContactUs\" >\r\n\r\n    <section id=\"cta\" class=\"cta \">\r\n        <div class=\"container\">\r\n            <h3 class=\"cta_title\">Contato.<\/h3>\r\n            <a class=\"cta_button button\" href=\"https:\/\/xcaliburmp.com\/pt-pt\/contato\/\" target=\"\" title=\"PREENCHA O FORMUL\u00c1RIO\">PREENCHA O FORMUL\u00c1RIO<\/a>\r\n        <\/div>\r\n    <\/section><!-- .cta -->\r\n\r\n\r\n    <\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-10043","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tecnologias - Xcalibur Smart Mapping<\/title>\n<meta name=\"description\" content=\"Oferecemos tecnologias inovadoras que permitem uma explora\u00e7\u00e3o eficiente de alvos por meio da aquisi\u00e7\u00e3o, an\u00e1lise e interpreta\u00e7\u00e3o de dados aerotransportados, reduzindo o impacto ambiental\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xcaliburmp.com\/pt-pt\/tecnologias\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tecnologias - Xcalibur Smart Mapping\" \/>\n<meta property=\"og:description\" content=\"Oferecemos tecnologias inovadoras que permitem uma explora\u00e7\u00e3o eficiente de alvos por meio da aquisi\u00e7\u00e3o, an\u00e1lise e interpreta\u00e7\u00e3o de dados aerotransportados, reduzindo o impacto ambiental\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xcaliburmp.com\/pt-pt\/tecnologias\/\" \/>\n<meta property=\"og:site_name\" content=\"Xcalibur Smart Mapping\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-15T12:28:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xcaliburmp.com\\\/pt-pt\\\/tecnologias\\\/\",\"url\":\"https:\\\/\\\/xcaliburmp.com\\\/pt-pt\\\/tecnologias\\\/\",\"name\":\"Tecnologias - Xcalibur Smart Mapping\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xcaliburmp.com\\\/pt-pt\\\/#website\"},\"datePublished\":\"2025-07-15T09:46:34+00:00\",\"dateModified\":\"2025-07-15T12:28:03+00:00\",\"description\":\"Oferecemos tecnologias inovadoras que permitem uma explora\u00e7\u00e3o eficiente de alvos por meio da aquisi\u00e7\u00e3o, an\u00e1lise e interpreta\u00e7\u00e3o de dados aerotransportados, reduzindo o impacto ambiental\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xcaliburmp.com\\\/pt-pt\\\/tecnologias\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xcaliburmp.com\\\/pt-pt\\\/tecnologias\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xcaliburmp.com\\\/pt-pt\\\/tecnologias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/xcaliburmp.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tecnologias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xcaliburmp.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/xcaliburmp.com\\\/pt-pt\\\/\",\"name\":\"Xcalibur Smart Mapping\",\"description\":\"Xcalibur Smart Mapping es un l\u00edder mundial en geof\u00edsica a\u00e9rea y marina, interpretaci\u00f3n y procesamiento de datos y servicios de valor agregado.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xcaliburmp.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tecnologias - Xcalibur Smart Mapping","description":"Oferecemos tecnologias inovadoras que permitem uma explora\u00e7\u00e3o eficiente de alvos por meio da aquisi\u00e7\u00e3o, an\u00e1lise e interpreta\u00e7\u00e3o de dados aerotransportados, reduzindo o impacto ambiental","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xcaliburmp.com\/pt-pt\/tecnologias\/","og_locale":"pt_PT","og_type":"article","og_title":"Tecnologias - Xcalibur Smart Mapping","og_description":"Oferecemos tecnologias inovadoras que permitem uma explora\u00e7\u00e3o eficiente de alvos por meio da aquisi\u00e7\u00e3o, an\u00e1lise e interpreta\u00e7\u00e3o de dados aerotransportados, reduzindo o impacto ambiental","og_url":"https:\/\/xcaliburmp.com\/pt-pt\/tecnologias\/","og_site_name":"Xcalibur Smart Mapping","article_modified_time":"2025-07-15T12:28:03+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xcaliburmp.com\/pt-pt\/tecnologias\/","url":"https:\/\/xcaliburmp.com\/pt-pt\/tecnologias\/","name":"Tecnologias - Xcalibur Smart Mapping","isPartOf":{"@id":"https:\/\/xcaliburmp.com\/pt-pt\/#website"},"datePublished":"2025-07-15T09:46:34+00:00","dateModified":"2025-07-15T12:28:03+00:00","description":"Oferecemos tecnologias inovadoras que permitem uma explora\u00e7\u00e3o eficiente de alvos por meio da aquisi\u00e7\u00e3o, an\u00e1lise e interpreta\u00e7\u00e3o de dados aerotransportados, reduzindo o impacto ambiental","breadcrumb":{"@id":"https:\/\/xcaliburmp.com\/pt-pt\/tecnologias\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xcaliburmp.com\/pt-pt\/tecnologias\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/xcaliburmp.com\/pt-pt\/tecnologias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/xcaliburmp.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Tecnologias"}]},{"@type":"WebSite","@id":"https:\/\/xcaliburmp.com\/pt-pt\/#website","url":"https:\/\/xcaliburmp.com\/pt-pt\/","name":"Xcalibur Smart Mapping","description":"Xcalibur Smart Mapping es un l\u00edder mundial en geof\u00edsica a\u00e9rea y marina, interpretaci\u00f3n y procesamiento de datos y servicios de valor agregado.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xcaliburmp.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/xcaliburmp.com\/pt-pt\/wp-json\/wp\/v2\/pages\/10043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xcaliburmp.com\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/xcaliburmp.com\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"replies":[{"embeddable":true,"href":"https:\/\/xcaliburmp.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=10043"}],"version-history":[{"count":25,"href":"https:\/\/xcaliburmp.com\/pt-pt\/wp-json\/wp\/v2\/pages\/10043\/revisions"}],"predecessor-version":[{"id":10346,"href":"https:\/\/xcaliburmp.com\/pt-pt\/wp-json\/wp\/v2\/pages\/10043\/revisions\/10346"}],"wp:attachment":[{"href":"https:\/\/xcaliburmp.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=10043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}